{"id":17813,"date":"2025-09-05T13:37:29","date_gmt":"2025-09-05T13:37:29","guid":{"rendered":"https:\/\/mercyships.africa\/kekeh-driver-from-freetown-relieved-of-painful-hernia-in-first-surgery-on-board-global-mercy\/"},"modified":"2025-09-05T13:48:41","modified_gmt":"2025-09-05T13:48:41","slug":"un-conducteur-de-tuk-tuk-de-freetown-premier-patient-opere-et-libere-de-ses-souffrances-a-bord-du-global-mercy","status":"publish","type":"post","link":"https:\/\/mercyships.africa\/fr\/un-conducteur-de-tuk-tuk-de-freetown-premier-patient-opere-et-libere-de-ses-souffrances-a-bord-du-global-mercy\/","title":{"rendered":"Un conducteur de tuk-tuk de Freetown, premier patient op\u00e9r\u00e9 et lib\u00e9r\u00e9 de ses souffrances \u00e0 bord du Global Mercy"},"content":{"rendered":"\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-2g58hqc-4bbbe815e9486761a04f65339007ced9\">\n.flex_column.av-2g58hqc-4bbbe815e9486761a04f65339007ced9{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-2g58hqc-4bbbe815e9486761a04f65339007ced9 av_one_full  avia-builder-el-0  el_before_av_textblock  avia-builder-el-first  first flex_column_div av-zero-column-padding  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-1xch2ec-3c4a6c6817c128344ef33e4c31f359e8\">\n#top .hr.hr-invisible.av-1xch2ec-3c4a6c6817c128344ef33e4c31f359e8{\nheight:100px;\n}\n<\/style>\n<div  class='hr av-1xch2ec-3c4a6c6817c128344ef33e4c31f359e8 hr-invisible  avia-builder-el-1  avia-builder-el-no-sibling  av-small-hide av-mini-hide'><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><\/div>\n<section  class='av_textblock_section av-mf6u7cst-cb45eb271be7afab2d13483767abbeb5 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class='avia_textblock'  itemprop=\"text\" ><h3 style=\"text-align: center\">Un conducteur de tuk-tuk de Freetown, premier patient op\u00e9r\u00e9 et lib\u00e9r\u00e9 de ses souffrances \u00e0 bord du <em>Global Mercy<\/em><\/h3>\n<div id=\"attachment_17807\" style=\"width: 1040px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-17807\" class=\"wp-image-17807 size-large\" src=\"https:\/\/mercyships.africa\/wp-content\/uploads\/2025\/09\/SLH250830_MOHAMED_SLH03522_BEFORE_HOMEVISIT_RU014_HI-MID-1030x686.jpg\" alt=\"\" width=\"1030\" height=\"686\" srcset=\"https:\/\/mercyships.africa\/wp-content\/uploads\/2025\/09\/SLH250830_MOHAMED_SLH03522_BEFORE_HOMEVISIT_RU014_HI-MID-1030x686.jpg 1030w, https:\/\/mercyships.africa\/wp-content\/uploads\/2025\/09\/SLH250830_MOHAMED_SLH03522_BEFORE_HOMEVISIT_RU014_HI-MID-300x200.jpg 300w, https:\/\/mercyships.africa\/wp-content\/uploads\/2025\/09\/SLH250830_MOHAMED_SLH03522_BEFORE_HOMEVISIT_RU014_HI-MID-768x512.jpg 768w, https:\/\/mercyships.africa\/wp-content\/uploads\/2025\/09\/SLH250830_MOHAMED_SLH03522_BEFORE_HOMEVISIT_RU014_HI-MID-1536x1024.jpg 1536w, https:\/\/mercyships.africa\/wp-content\/uploads\/2025\/09\/SLH250830_MOHAMED_SLH03522_BEFORE_HOMEVISIT_RU014_HI-MID-1500x1000.jpg 1500w, https:\/\/mercyships.africa\/wp-content\/uploads\/2025\/09\/SLH250830_MOHAMED_SLH03522_BEFORE_HOMEVISIT_RU014_HI-MID-705x470.jpg 705w, https:\/\/mercyships.africa\/wp-content\/uploads\/2025\/09\/SLH250830_MOHAMED_SLH03522_BEFORE_HOMEVISIT_RU014_HI-MID.jpg 2000w\" sizes=\"auto, (max-width: 1030px) 100vw, 1030px\" \/><p id=\"caption-attachment-17807\" class=\"wp-caption-text\">Mohamed, premier patient de la mission en Sierra Leone, lors d&rsquo;une visite \u00e0 domicile avant son op\u00e9ration.<\/p><\/div>\n<p><strong>Freetown, Sierra Leone \u2013 2 septembre 2025.<\/strong>\u00a0Le\u00a0<em>Global Mercy\u2122<\/em>, le plus grand navire-h\u00f4pital civil au monde exploit\u00e9 par l\u2019ONG Mercy Ships, a officiellement d\u00e9marr\u00e9 sa troisi\u00e8me mission cons\u00e9cutive en Sierra Leone, marqu\u00e9e par l\u2019intervention du premier patient, Mohamed, un conducteur de tuk-tuk de 40 ans. Ce moment cl\u00e9 marque le renouvellement de la mission d\u00e9di\u00e9e \u00e0 l\u2019espoir et la gu\u00e9rison tout en renfor\u00e7ant les syst\u00e8mes anesth\u00e9siques et chirurgicaux du pays.<\/p>\n<p>Pendant plus de cinq ans, tout en parcourant les rues anim\u00e9es de Freetown sur son tricycle motoris\u00e9 pour subvenir aux besoins de sa femme et de ses quatre enfants, Mohamed a souffert quotidiennement d&rsquo;une hernie et malgr\u00e9 une g\u00eane constante, la crainte des complications l&#8217;emp\u00eachait de se faire op\u00e9rer.<\/p>\n<p>Contrairement aux pays \u00e0 revenu \u00e9lev\u00e9, les hernies restent souvent non trait\u00e9es en Sierra Leone. <a href=\"https:\/\/pmc.ncbi.nlm.nih.gov\/articles\/PMC4852727\/\">Une enqu\u00eate d\u00e9mographique<\/a> a r\u00e9v\u00e9l\u00e9 une pr\u00e9valence de 7,7 % des hernies chez les hommes adultes, l&rsquo;une des plus \u00e9lev\u00e9es au monde.<\/p>\n<div id=\"attachment_17799\" style=\"width: 1040px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-17799\" class=\"wp-image-17799 size-large\" src=\"https:\/\/mercyships.africa\/wp-content\/uploads\/2025\/09\/SLH250901_MOHAMED_SLH03522_BEFORE_ADMISSION_ZWIACHER_RU016_HI-MID-1030x686.jpg\" alt=\"\" width=\"1030\" height=\"686\" srcset=\"https:\/\/mercyships.africa\/wp-content\/uploads\/2025\/09\/SLH250901_MOHAMED_SLH03522_BEFORE_ADMISSION_ZWIACHER_RU016_HI-MID-1030x686.jpg 1030w, https:\/\/mercyships.africa\/wp-content\/uploads\/2025\/09\/SLH250901_MOHAMED_SLH03522_BEFORE_ADMISSION_ZWIACHER_RU016_HI-MID-300x200.jpg 300w, https:\/\/mercyships.africa\/wp-content\/uploads\/2025\/09\/SLH250901_MOHAMED_SLH03522_BEFORE_ADMISSION_ZWIACHER_RU016_HI-MID-768x512.jpg 768w, https:\/\/mercyships.africa\/wp-content\/uploads\/2025\/09\/SLH250901_MOHAMED_SLH03522_BEFORE_ADMISSION_ZWIACHER_RU016_HI-MID-1536x1024.jpg 1536w, https:\/\/mercyships.africa\/wp-content\/uploads\/2025\/09\/SLH250901_MOHAMED_SLH03522_BEFORE_ADMISSION_ZWIACHER_RU016_HI-MID-1500x1000.jpg 1500w, https:\/\/mercyships.africa\/wp-content\/uploads\/2025\/09\/SLH250901_MOHAMED_SLH03522_BEFORE_ADMISSION_ZWIACHER_RU016_HI-MID-705x470.jpg 705w, https:\/\/mercyships.africa\/wp-content\/uploads\/2025\/09\/SLH250901_MOHAMED_SLH03522_BEFORE_ADMISSION_ZWIACHER_RU016_HI-MID.jpg 2000w\" sizes=\"auto, (max-width: 1030px) 100vw, 1030px\" \/><p id=\"caption-attachment-17799\" class=\"wp-caption-text\">Mohamed, avec John Zwiacher, chirurgien g\u00e9n\u00e9raliste, lors de son admission.<\/p><\/div>\n<p>Lorsque Mohamed a appris que le <em>Global Mercy<\/em> revenait en Sierra Leone, il a trouv\u00e9 le courage de s&rsquo;inscrire. Le 29 ao\u00fbt, apr\u00e8s un examen m\u00e9dical approfondi, il a pu recevoir une intervention chirurgicale, marquant ainsi le d\u00e9but officiel de cette nouvelle mission.<\/p>\n<p>La veille, une c\u00e9r\u00e9monie de bienvenue organis\u00e9e \u00e0 bord du\u00a0<em>Global Mercy<\/em> a officiellement inaugur\u00e9 cette nouvelle mission. Des dirigeants gouvernementaux, des membres du corps diplomatique, des repr\u00e9sentants d&rsquo;\u00e9glises, d&rsquo;organisations \u00e0 but non lucratif et du secteur priv\u00e9 se sont r\u00e9unis pour c\u00e9l\u00e9brer ce nouveau chapitre. L&rsquo;\u00e9v\u00e9nement a permis de rappeler les r\u00e9alisations pass\u00e9es et de d\u00e9finir une vision pleine d&rsquo;espoir pour l\u2019avenir.<\/p>\n<p>C\u2019est avec \u00e9motion que le vice-pr\u00e9sident Mohamed Juldeh Jalloh a \u00e9voqu\u00e9 l&rsquo;impact du travail de Mercy Ships :<\/p>\n<p><em>\u00ab Mercy Ships a dispens\u00e9 des services chirurgicaux \u00e0 des enfants qui ont ensuite pu r\u00e9int\u00e9grer le syst\u00e8me scolaire et leurs communaut\u00e9s. Ce service redonne espoir et dignit\u00e9 aux patients qui retrouvent la vue et, surtout, soutient des pays comme la Sierra Leone qui s&rsquo;efforcent de renforcer leur personnel de sant\u00e9. \u00bb<\/em><em>\u00a0<\/em><\/p>\n<p>Ces derniers jours, l&rsquo;h\u00f4pital flottant s&rsquo;est pr\u00e9par\u00e9 au d\u00e9marrage des interventions chirurgicales et toute la communaut\u00e9 hospitali\u00e8re lui a rendu gr\u00e2ce.<\/p>\n<p><em>\u00ab Cette \u00e9tape importante marque non seulement le d\u00e9but d&rsquo;une nouvelle mission, mais t\u00e9moigne \u00e9galement avec force du d\u00e9vouement incroyable de nos b\u00e9n\u00e9voles, dont l&rsquo;engagement rend notre mission possible chaque jour\u00a0\u00bb,<\/em> a d\u00e9clar\u00e9 le Dr Steven Purdon, le nouveau Directeur de l\u2019h\u00f4pital.<\/p>\n<div id=\"attachment_17803\" style=\"width: 1040px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-17803\" class=\"wp-image-17803 size-large\" style=\"font-family: Georgia, 'Times New Roman', 'Bitstream Charter', Times, serif;font-size: 16px\" src=\"https:\/\/mercyships.africa\/wp-content\/uploads\/2025\/09\/SLH250902_MOHAMED_SLH03522_SURGERY_DAY_PRAYER_RU007_HI-MID-1030x686.jpg\" alt=\"\" width=\"1030\" height=\"686\" srcset=\"https:\/\/mercyships.africa\/wp-content\/uploads\/2025\/09\/SLH250902_MOHAMED_SLH03522_SURGERY_DAY_PRAYER_RU007_HI-MID-1030x686.jpg 1030w, https:\/\/mercyships.africa\/wp-content\/uploads\/2025\/09\/SLH250902_MOHAMED_SLH03522_SURGERY_DAY_PRAYER_RU007_HI-MID-300x200.jpg 300w, https:\/\/mercyships.africa\/wp-content\/uploads\/2025\/09\/SLH250902_MOHAMED_SLH03522_SURGERY_DAY_PRAYER_RU007_HI-MID-768x512.jpg 768w, https:\/\/mercyships.africa\/wp-content\/uploads\/2025\/09\/SLH250902_MOHAMED_SLH03522_SURGERY_DAY_PRAYER_RU007_HI-MID-1536x1024.jpg 1536w, https:\/\/mercyships.africa\/wp-content\/uploads\/2025\/09\/SLH250902_MOHAMED_SLH03522_SURGERY_DAY_PRAYER_RU007_HI-MID-1500x1000.jpg 1500w, https:\/\/mercyships.africa\/wp-content\/uploads\/2025\/09\/SLH250902_MOHAMED_SLH03522_SURGERY_DAY_PRAYER_RU007_HI-MID-705x470.jpg 705w, https:\/\/mercyships.africa\/wp-content\/uploads\/2025\/09\/SLH250902_MOHAMED_SLH03522_SURGERY_DAY_PRAYER_RU007_HI-MID.jpg 2000w\" sizes=\"auto, (max-width: 1030px) 100vw, 1030px\" \/><p id=\"caption-attachment-17803\" class=\"wp-caption-text\">L&rsquo;\u00e9quipage prie pour Mohamed avant son op\u00e9ration.<\/p><\/div>\n<p>Le week-end pr\u00e9c\u00e9dant l&rsquo;op\u00e9ration de Mohamed, le chirurgien b\u00e9n\u00e9vole Dr John Zwiacher, originaire d&rsquo;Alaska, est arriv\u00e9 \u00e0 Freetown pour rejoindre l&rsquo;\u00e9quipe internationale de professionnels de sant\u00e9 \u00e0 bord. Ses neuf missions avec Mercy Ships lui permettent de souligner la force de cette mission\u00a0:<\/p>\n<p>\u00ab <em>Nous sommes tous issus des quatre coins du monde, du Canada, des \u00c9tats-Unis, du Royaume-Uni, de Su\u00e8de et de bien d&rsquo;autres pays encore. Peu importe notre langue ou notre origine, nous partageons tous le m\u00eame objectif : op\u00e9rer et soigner les patients<\/em>. \u00bb<\/p>\n<p>L&rsquo;op\u00e9ration d&rsquo;une heure subie par Mohamed \u00e0 bord du\u00a0<em>Global Mercy<\/em><em>\u00a0<\/em>a permis de retirer sa hernie, marquant ainsi le d\u00e9but officiel de cette nouvelle mission en Sierra Leone. Pour Mohamed, c\u2019est un tournant dans sa vie. Non seulement d\u00e9barrass\u00e9 de la douleur de sa hernie, il a aussi retrouv\u00e9 sa dignit\u00e9, un soulagement et de l&rsquo;espoir pour l&rsquo;avenir de sa famille.<\/p>\n<p>Avec l&rsquo;op\u00e9ration de Mohamed, le\u00a0<em>Global Mercy<\/em>\u00a0a d\u00e9marr\u00e9 officiellement sa mission et se pr\u00e9pare \u00e0 accueillir de nombreux autres patients \u00e0 son bord.<\/p>\n<div id=\"attachment_17805\" style=\"width: 1040px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-17805\" class=\"wp-image-17805 size-large\" style=\"font-family: Georgia, 'Times New Roman', 'Bitstream Charter', Times, serif;font-size: 16px\" src=\"https:\/\/mercyships.africa\/wp-content\/uploads\/2025\/09\/SLH250902_MOHAMED_SLH03522_SURGERY_OR_ZWIACHER_RU010_HI-MID-1030x687.jpg\" alt=\"\" width=\"1030\" height=\"687\" srcset=\"https:\/\/mercyships.africa\/wp-content\/uploads\/2025\/09\/SLH250902_MOHAMED_SLH03522_SURGERY_OR_ZWIACHER_RU010_HI-MID-1030x687.jpg 1030w, https:\/\/mercyships.africa\/wp-content\/uploads\/2025\/09\/SLH250902_MOHAMED_SLH03522_SURGERY_OR_ZWIACHER_RU010_HI-MID-300x200.jpg 300w, https:\/\/mercyships.africa\/wp-content\/uploads\/2025\/09\/SLH250902_MOHAMED_SLH03522_SURGERY_OR_ZWIACHER_RU010_HI-MID-768x512.jpg 768w, https:\/\/mercyships.africa\/wp-content\/uploads\/2025\/09\/SLH250902_MOHAMED_SLH03522_SURGERY_OR_ZWIACHER_RU010_HI-MID-1536x1025.jpg 1536w, https:\/\/mercyships.africa\/wp-content\/uploads\/2025\/09\/SLH250902_MOHAMED_SLH03522_SURGERY_OR_ZWIACHER_RU010_HI-MID-1500x1001.jpg 1500w, https:\/\/mercyships.africa\/wp-content\/uploads\/2025\/09\/SLH250902_MOHAMED_SLH03522_SURGERY_OR_ZWIACHER_RU010_HI-MID-705x470.jpg 705w, https:\/\/mercyships.africa\/wp-content\/uploads\/2025\/09\/SLH250902_MOHAMED_SLH03522_SURGERY_OR_ZWIACHER_RU010_HI-MID.jpg 2000w\" sizes=\"auto, (max-width: 1030px) 100vw, 1030px\" \/><p id=\"caption-attachment-17805\" class=\"wp-caption-text\">John Zwiacher, chirurgien g\u00e9n\u00e9raliste, op\u00e9rant Mohamed.<\/p><\/div>\n<p><strong>\u00c0 PROPOS DE MERCY SHIPS :<\/strong><\/p>\n<p>Mercy Ships est une organisation humanitaire internationale qui d\u00e9ploie les deux plus grands navires-h\u00f4pitaux civils au monde, l\u2019<em>Africa Mercy\u00ae<\/em> et le <em>Global Mercy<\/em><em>\u2122<\/em>, pour fournir des soins de sant\u00e9 gratuits et de premi\u00e8re qualit\u00e9 aux plus d\u00e9munis. L\u2019ONG internationale soutient \u00e9galement le d\u00e9veloppement des syst\u00e8mes de sant\u00e9 des pays h\u00f4tes par la formation des professionnels de la sant\u00e9 et la r\u00e9novation d\u2019infrastructures.<\/p>\n<p>Fond\u00e9 en Suisse en 1978 par Don et Deyon Stephens, Mercy Ships est intervenu dans 55 pays. A bord de ses navires, une moyenne de 2 500 b\u00e9n\u00e9voles par an, issus de 60 pays, contribuent \u00e0 l&rsquo;\u0153uvre de Mercy Ships. Des professionnels tels que chirurgiens, dentistes, personnel infirmier, formateurs dans le domaine de la sant\u00e9, cuisiniers, marins, ing\u00e9nieurs et agriculteurs d\u00e9dient leur temps et leurs comp\u00e9tences \u00e0 cette cause. Avec des bureaux dans 16 pays et un Centre op\u00e9rationnel pour l&rsquo;Afrique bas\u00e9 \u00e0 Dakar, au S\u00e9n\u00e9gal, Mercy Ships se met au service des nations en restaurant sant\u00e9 et dignit\u00e9.<\/p>\n<p>Pour plus d&rsquo;informations sur Mercy Ships, veuillez contacter <a href=\"mailto:international.media@mercyships.org\">international.media@mercyships.org<\/a><\/p>\n<\/div><\/section>\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='av_section_1'  class='avia-section av-1fvzw84-06472ddaaf004d81ee40d857043d05fe main_color avia-section-default avia-no-border-styling  avia-builder-el-3  el_after_av_textblock  avia-builder-el-last  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-17813'><div class='entry-content-wrapper clearfix'>\n<div  class='avia-button-wrap av-3o06jo-755bd74cf2de50873d45faa50ca22bad-wrap avia-button-center  avia-builder-el-4  el_before_av_blog  avia-builder-el-first '><a href='https:\/\/mercyships.africa\/news\/'  class='avia-button av-3o06jo-755bd74cf2de50873d45faa50ca22bad av-link-btn avia-icon_select-no avia-size-small avia-position-center avia-color-theme-color-subtle'   aria-label=\"Back to News\"><span class='avia_iconbox_title' >Back to News<\/span><\/a><\/div>\n<div  data-slideshow-options=\"{&quot;animation&quot;:&quot;fade&quot;,&quot;autoplay&quot;:false,&quot;loop_autoplay&quot;:&quot;once&quot;,&quot;interval&quot;:5,&quot;loop_manual&quot;:&quot;manual-endless&quot;,&quot;autoplay_stopper&quot;:false,&quot;noNavigation&quot;:false,&quot;show_slide_delay&quot;:90}\" class='avia-content-slider avia-content-grid-active avia-content-slider1 avia-content-slider-odd  avia-builder-el-5  el_after_av_button  avia-builder-el-last  av-slideshow-ui av-control-default   av-no-slider-navigation av-slideshow-manual av-loop-once av-loop-manual-endless '  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Blog\" ><div class=\"avia-content-slider-inner\"><div class=\"slide-entry-wrap\"><article class='slide-entry flex_column  post-entry post-entry-6564 slide-entry-overview slide-loop-1 slide-parity-odd  av_one_third first real-thumbnail posttype-post post-format-standard'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><a href='https:\/\/mercyships.africa\/fr\/le-plus-grand-navire-hopital-civil-au-monde-le-global-mercy-en-route-vers-le-senegal-au-mois-de-juin\/' data-rel='slide-1' class='slide-image' title='Le plus grand navire-h\u00f4pital civil au monde, le Global Mercy\u2122, en route vers le S\u00e9n\u00e9gal au mois de juin'><img decoding=\"async\" fetchpriority=\"high\" width=\"495\" height=\"400\" src=\"https:\/\/mercyships.africa\/wp-content\/uploads\/2022\/02\/NLD220311_GLM_ROTTERDAM_SENEGAL_DELEGATION_EV006_MID-495x400.jpg\" class=\"wp-image-6556 avia-img-lazy-loading-not-6556 attachment-portfolio size-portfolio wp-post-image\" alt=\"\" srcset=\"https:\/\/mercyships.africa\/wp-content\/uploads\/2022\/02\/NLD220311_GLM_ROTTERDAM_SENEGAL_DELEGATION_EV006_MID-495x400.jpg 495w, https:\/\/mercyships.africa\/wp-content\/uploads\/2022\/02\/NLD220311_GLM_ROTTERDAM_SENEGAL_DELEGATION_EV006_MID-845x684.jpg 845w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/><\/a><div class=\"slide-content\"><header class=\"entry-content-header\" aria-label=\"Slide: Le plus grand navire-h\u00f4pital civil au monde, le Global Mercy\u2122, en route vers le S\u00e9n\u00e9gal au mois de juin\"><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/mercyships.africa\/fr\/le-plus-grand-navire-hopital-civil-au-monde-le-global-mercy-en-route-vers-le-senegal-au-mois-de-juin\/' title='Le plus grand navire-h\u00f4pital civil au monde, le Global Mercy\u2122, en route vers le S\u00e9n\u00e9gal au mois de juin'>Le plus grand navire-h\u00f4pital civil au monde, le Global Mercy\u2122, en route vers le S\u00e9n\u00e9gal au mois de juin<\/a><\/h3><span class=\"blog-categories minor-meta\"><a href=\"https:\/\/mercyships.africa\/fr\/category\/communique-de-presse\/\" rel=\"tag\">Communiqu\u00e9 de presse<\/a> <\/span><span class=\"av-vertical-delimiter\"><\/span><\/header><\/div><footer class=\"entry-footer\"><\/footer><span class='hidden'>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" >\n\t\t\t\t\t\t<span itemprop='url'>https:\/\/mercyships.africa\/wp-content\/uploads\/2022\/02\/NLD220311_GLM_ROTTERDAM_SENEGAL_DELEGATION_EV006_MID.jpg<\/span>\n\t\t\t\t\t\t<span itemprop='height'>1333<\/span>\n\t\t\t\t\t\t<span itemprop='width'>2000<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"publisher\" itemtype=\"https:\/\/schema.org\/Organization\" itemscope=\"itemscope\" >\n\t\t\t\t\t\t<span itemprop='name'>shawnthompson<\/span>\n\t\t\t\t\t\t<span itemprop='logo' itemscope itemtype='https:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t\t<span itemprop='url'>https:\/\/mercyships.africa\/wp-content\/uploads\/2022\/04\/mercy-ships-logo-menu-africa-300x138.png<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t<\/span><span class='av-structured-data'  itemprop=\"author\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><span itemprop='name'>shawnthompson<\/span><\/span><span class='av-structured-data'  itemprop=\"datePublished\" datetime=\"2025-09-05T13:37:29+00:00\" >2022-03-30 19:10:29<\/span><span class='av-structured-data'  itemprop=\"dateModified\" itemtype=\"https:\/\/schema.org\/dateModified\" >2023-10-16 18:44:06<\/span><span class='av-structured-data'  itemprop=\"mainEntityOfPage\" itemtype=\"https:\/\/schema.org\/mainEntityOfPage\" ><span itemprop='name'>Le plus grand navire-h\u00f4pital civil au monde, le Global Mercy\u2122, en route vers le S\u00e9n\u00e9gal au mois de juin<\/span><\/span><\/span><\/article><article class='slide-entry flex_column  post-entry post-entry-14030 slide-entry-overview slide-loop-2 slide-parity-even  av_one_third  real-thumbnail posttype-post post-format-standard'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><a href='https:\/\/mercyships.africa\/fr\/the-msc-foundation-the-msc-group-and-mercy-ships-international-join-forces-to-build-a-new-hospital-ship\/' data-rel='slide-1' class='slide-image' title='LA FONDATION MSC, LE GROUPE MSC ET MERCY SHIPS INTERNATIONAL UNISSENT LEURS FORCES POUR CONSTRUIRE UN NOUVEAU NAVIRE-H\u00d4PITAL.'><img decoding=\"async\" fetchpriority=\"high\" width=\"495\" height=\"400\" src=\"https:\/\/mercyships.africa\/wp-content\/uploads\/2024\/04\/SNC220807_UMU_SNC07815_AFTER_DECK7_JM004_HI-MID-495x400.jpg\" class=\"wp-image-14013 avia-img-lazy-loading-not-14013 attachment-portfolio size-portfolio wp-post-image\" alt=\"\" srcset=\"https:\/\/mercyships.africa\/wp-content\/uploads\/2024\/04\/SNC220807_UMU_SNC07815_AFTER_DECK7_JM004_HI-MID-495x400.jpg 495w, https:\/\/mercyships.africa\/wp-content\/uploads\/2024\/04\/SNC220807_UMU_SNC07815_AFTER_DECK7_JM004_HI-MID-845x684.jpg 845w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/><\/a><div class=\"slide-content\"><header class=\"entry-content-header\" aria-label=\"Slide: LA FONDATION MSC, LE GROUPE MSC ET MERCY SHIPS INTERNATIONAL UNISSENT LEURS FORCES POUR CONSTRUIRE UN NOUVEAU NAVIRE-H\u00d4PITAL.\"><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/mercyships.africa\/fr\/the-msc-foundation-the-msc-group-and-mercy-ships-international-join-forces-to-build-a-new-hospital-ship\/' title='LA FONDATION MSC, LE GROUPE MSC ET MERCY SHIPS INTERNATIONAL UNISSENT LEURS FORCES POUR CONSTRUIRE UN NOUVEAU NAVIRE-H\u00d4PITAL.'>LA FONDATION MSC, LE GROUPE MSC ET MERCY SHIPS INTERNATIONAL UNISSENT LEURS FORCES POUR CONSTRUIRE UN NOUVEAU NAVIRE-H\u00d4PITAL.<\/a><\/h3><span class=\"blog-categories minor-meta\"><a href=\"https:\/\/mercyships.africa\/fr\/category\/communique-de-presse\/\" rel=\"tag\">Communiqu\u00e9 de presse<\/a> <\/span><span class=\"av-vertical-delimiter\"><\/span><\/header><\/div><footer class=\"entry-footer\"><\/footer><span class='hidden'>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" >\n\t\t\t\t\t\t<span itemprop='url'>https:\/\/mercyships.africa\/wp-content\/uploads\/2024\/04\/SNC220807_UMU_SNC07815_AFTER_DECK7_JM004_HI-MID.jpg<\/span>\n\t\t\t\t\t\t<span itemprop='height'>1335<\/span>\n\t\t\t\t\t\t<span itemprop='width'>2000<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"publisher\" itemtype=\"https:\/\/schema.org\/Organization\" itemscope=\"itemscope\" >\n\t\t\t\t\t\t<span itemprop='name'>globalbranding<\/span>\n\t\t\t\t\t\t<span itemprop='logo' itemscope itemtype='https:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t\t<span itemprop='url'>https:\/\/mercyships.africa\/wp-content\/uploads\/2022\/04\/mercy-ships-logo-menu-africa-300x138.png<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t<\/span><span class='av-structured-data'  itemprop=\"author\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><span itemprop='name'>globalbranding<\/span><\/span><span class='av-structured-data'  itemprop=\"datePublished\" datetime=\"2025-09-05T13:37:29+00:00\" >2024-04-22 18:39:15<\/span><span class='av-structured-data'  itemprop=\"dateModified\" itemtype=\"https:\/\/schema.org\/dateModified\" >2024-04-22 18:43:46<\/span><span class='av-structured-data'  itemprop=\"mainEntityOfPage\" itemtype=\"https:\/\/schema.org\/mainEntityOfPage\" ><span itemprop='name'>LA FONDATION MSC, LE GROUPE MSC ET MERCY SHIPS INTERNATIONAL UNISSENT LEURS FORCES POUR CONSTRUIRE UN NOUVEAU NAVIRE-H\u00d4PITAL.<\/span><\/span><\/span><\/article><article class='slide-entry flex_column  post-entry post-entry-17088 slide-entry-overview slide-loop-3 slide-parity-odd  post-entry-last  av_one_third  real-thumbnail posttype-post post-format-standard'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><a href='https:\/\/mercyships.africa\/fr\/de-lengagement-a-laction-les-dirigeants-unissent-leurs-voix-pour-reduire-les-inegalites-dacces-a-la-chirurgie\/' data-rel='slide-1' class='slide-image' title='De l\u2019engagement \u00e0 l\u2019action : les dirigeants unissent leurs voix  pour r\u00e9duire les in\u00e9galit\u00e9s d\u2019acc\u00e8s \u00e0 la chirurgie'><img decoding=\"async\" fetchpriority=\"high\" width=\"495\" height=\"400\" src=\"https:\/\/mercyships.africa\/wp-content\/uploads\/2025\/06\/Image-4-495x400.jpeg\" class=\"wp-image-17081 avia-img-lazy-loading-not-17081 attachment-portfolio size-portfolio wp-post-image\" alt=\"\" srcset=\"https:\/\/mercyships.africa\/wp-content\/uploads\/2025\/06\/Image-4-495x400.jpeg 495w, https:\/\/mercyships.africa\/wp-content\/uploads\/2025\/06\/Image-4-845x684.jpeg 845w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/><\/a><div class=\"slide-content\"><header class=\"entry-content-header\" aria-label=\"Slide: De l\u2019engagement \u00e0 l\u2019action : les dirigeants unissent leurs voix  pour r\u00e9duire les in\u00e9galit\u00e9s d\u2019acc\u00e8s \u00e0 la chirurgie\"><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/mercyships.africa\/fr\/de-lengagement-a-laction-les-dirigeants-unissent-leurs-voix-pour-reduire-les-inegalites-dacces-a-la-chirurgie\/' title='De l\u2019engagement \u00e0 l\u2019action : les dirigeants unissent leurs voix  pour r\u00e9duire les in\u00e9galit\u00e9s d\u2019acc\u00e8s \u00e0 la chirurgie'>De l\u2019engagement \u00e0 l\u2019action : les dirigeants unissent leurs voix  pour r\u00e9duire les in\u00e9galit\u00e9s d\u2019acc\u00e8s \u00e0 la chirurgie<\/a><\/h3><span class=\"blog-categories minor-meta\"><a href=\"https:\/\/mercyships.africa\/fr\/category\/actualites\/\" rel=\"tag\">Actualit\u00e9s<\/a>, <a href=\"https:\/\/mercyships.africa\/fr\/category\/communique-de-presse\/\" rel=\"tag\">Communiqu\u00e9 de presse<\/a> <\/span><span class=\"av-vertical-delimiter\"><\/span><\/header><\/div><footer class=\"entry-footer\"><\/footer><span class='hidden'>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" >\n\t\t\t\t\t\t<span itemprop='url'>https:\/\/mercyships.africa\/wp-content\/uploads\/2025\/06\/Image-4.jpeg<\/span>\n\t\t\t\t\t\t<span itemprop='height'>1200<\/span>\n\t\t\t\t\t\t<span itemprop='width'>1600<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"publisher\" itemtype=\"https:\/\/schema.org\/Organization\" itemscope=\"itemscope\" >\n\t\t\t\t\t\t<span itemprop='name'>globalbranding<\/span>\n\t\t\t\t\t\t<span itemprop='logo' itemscope itemtype='https:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t\t<span itemprop='url'>https:\/\/mercyships.africa\/wp-content\/uploads\/2022\/04\/mercy-ships-logo-menu-africa-300x138.png<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t<\/span><span class='av-structured-data'  itemprop=\"author\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><span itemprop='name'>globalbranding<\/span><\/span><span class='av-structured-data'  itemprop=\"datePublished\" datetime=\"2025-09-05T13:37:29+00:00\" >2025-06-14 14:03:14<\/span><span class='av-structured-data'  itemprop=\"dateModified\" itemtype=\"https:\/\/schema.org\/dateModified\" >2025-06-14 14:11:10<\/span><span class='av-structured-data'  itemprop=\"mainEntityOfPage\" itemtype=\"https:\/\/schema.org\/mainEntityOfPage\" ><span itemprop='name'>De l\u2019engagement \u00e0 l\u2019action : les dirigeants unissent leurs voix  pour r\u00e9duire les in\u00e9galit\u00e9s d\u2019acc\u00e8s \u00e0 la chirurgie<\/span><\/span><\/span><\/article><\/div><\/div><\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Freetown, Sierra Leone \u2013 2 septembre 2025. Le Global Mercy\u2122, le plus grand navire-h\u00f4pital civil au monde exploit\u00e9 par l\u2019ONG Mercy Ships, a officiellement d\u00e9marr\u00e9 sa troisi\u00e8me mission cons\u00e9cutive en Sierra Leone, marqu\u00e9e par l\u2019intervention du premier patient, Mohamed, un conducteur de tuk-tuk de 40 ans. Ce moment cl\u00e9 marque le renouvellement de la mission d\u00e9di\u00e9e \u00e0 l\u2019espoir et la gu\u00e9rison tout en renfor\u00e7ant les syst\u00e8mes anesth\u00e9siques et chirurgicaux du pays. <\/p>\n","protected":false},"author":7,"featured_media":17809,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[10,9],"tags":[32,54,106,33,65,89],"class_list":["post-17813","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","category-communique-de-presse","tag-africa-fr","tag-global-mercy-fr","tag-global-surgery-fr","tag-mercy-ships-fr","tag-sierra-leone-fr","tag-surgery-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un conducteur de tuk-tuk de Freetown, premier patient op\u00e9r\u00e9 et lib\u00e9r\u00e9 de ses souffrances \u00e0 bord du Global Mercy - Mercy Ships Africa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mercyships.africa\/fr\/un-conducteur-de-tuk-tuk-de-freetown-premier-patient-opere-et-libere-de-ses-souffrances-a-bord-du-global-mercy\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un conducteur de tuk-tuk de Freetown, premier patient op\u00e9r\u00e9 et lib\u00e9r\u00e9 de ses souffrances \u00e0 bord du Global Mercy - Mercy Ships Africa\" \/>\n<meta property=\"og:description\" content=\"Freetown, Sierra Leone \u2013 2 septembre 2025. Le Global Mercy\u2122, le plus grand navire-h\u00f4pital civil au monde exploit\u00e9 par l\u2019ONG Mercy Ships, a officiellement d\u00e9marr\u00e9 sa troisi\u00e8me mission cons\u00e9cutive en Sierra Leone, marqu\u00e9e par l\u2019intervention du premier patient, Mohamed, un conducteur de tuk-tuk de 40 ans. Ce moment cl\u00e9 marque le renouvellement de la mission d\u00e9di\u00e9e \u00e0 l\u2019espoir et la gu\u00e9rison tout en renfor\u00e7ant les syst\u00e8mes anesth\u00e9siques et chirurgicaux du pays.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mercyships.africa\/fr\/un-conducteur-de-tuk-tuk-de-freetown-premier-patient-opere-et-libere-de-ses-souffrances-a-bord-du-global-mercy\/\" \/>\n<meta property=\"og:site_name\" content=\"Mercy Ships Africa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mercyships.africa\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-05T13:37:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-05T13:48:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mercyships.africa\/wp-content\/uploads\/2025\/09\/SLH250901_MOHAMED_SLH03522_BEFORE_ADMISSION_GANGWAY_RU001_HI-LO.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"globalbranding\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@mercyshipsafb\" \/>\n<meta name=\"twitter:site\" content=\"@mercyshipsafb\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"globalbranding\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mercyships.africa\\\/fr\\\/un-conducteur-de-tuk-tuk-de-freetown-premier-patient-opere-et-libere-de-ses-souffrances-a-bord-du-global-mercy\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mercyships.africa\\\/fr\\\/un-conducteur-de-tuk-tuk-de-freetown-premier-patient-opere-et-libere-de-ses-souffrances-a-bord-du-global-mercy\\\/\"},\"author\":{\"name\":\"globalbranding\",\"@id\":\"https:\\\/\\\/mercyships.africa\\\/#\\\/schema\\\/person\\\/a4fe96ee15d570fe5cf8b99975f4d8b0\"},\"headline\":\"Un conducteur de tuk-tuk de Freetown, premier patient op\u00e9r\u00e9 et lib\u00e9r\u00e9 de ses souffrances \u00e0 bord du Global Mercy\",\"datePublished\":\"2025-09-05T13:37:29+00:00\",\"dateModified\":\"2025-09-05T13:48:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mercyships.africa\\\/fr\\\/un-conducteur-de-tuk-tuk-de-freetown-premier-patient-opere-et-libere-de-ses-souffrances-a-bord-du-global-mercy\\\/\"},\"wordCount\":1358,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/mercyships.africa\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mercyships.africa\\\/fr\\\/un-conducteur-de-tuk-tuk-de-freetown-premier-patient-opere-et-libere-de-ses-souffrances-a-bord-du-global-mercy\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mercyships.africa\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/SLH250901_MOHAMED_SLH03522_BEFORE_ADMISSION_GANGWAY_RU001_HI-LO.jpg\",\"keywords\":[\"Africa\",\"Global Mercy\",\"Global Surgery\",\"Mercy Ships\",\"Sierra Leone\",\"Surgery\"],\"articleSection\":[\"Actualit\u00e9s\",\"Communiqu\u00e9 de presse\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/mercyships.africa\\\/fr\\\/un-conducteur-de-tuk-tuk-de-freetown-premier-patient-opere-et-libere-de-ses-souffrances-a-bord-du-global-mercy\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mercyships.africa\\\/fr\\\/un-conducteur-de-tuk-tuk-de-freetown-premier-patient-opere-et-libere-de-ses-souffrances-a-bord-du-global-mercy\\\/\",\"url\":\"https:\\\/\\\/mercyships.africa\\\/fr\\\/un-conducteur-de-tuk-tuk-de-freetown-premier-patient-opere-et-libere-de-ses-souffrances-a-bord-du-global-mercy\\\/\",\"name\":\"Un conducteur de tuk-tuk de Freetown, premier patient op\u00e9r\u00e9 et lib\u00e9r\u00e9 de ses souffrances \u00e0 bord du Global Mercy - Mercy Ships Africa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mercyships.africa\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mercyships.africa\\\/fr\\\/un-conducteur-de-tuk-tuk-de-freetown-premier-patient-opere-et-libere-de-ses-souffrances-a-bord-du-global-mercy\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mercyships.africa\\\/fr\\\/un-conducteur-de-tuk-tuk-de-freetown-premier-patient-opere-et-libere-de-ses-souffrances-a-bord-du-global-mercy\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mercyships.africa\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/SLH250901_MOHAMED_SLH03522_BEFORE_ADMISSION_GANGWAY_RU001_HI-LO.jpg\",\"datePublished\":\"2025-09-05T13:37:29+00:00\",\"dateModified\":\"2025-09-05T13:48:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mercyships.africa\\\/fr\\\/un-conducteur-de-tuk-tuk-de-freetown-premier-patient-opere-et-libere-de-ses-souffrances-a-bord-du-global-mercy\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mercyships.africa\\\/fr\\\/un-conducteur-de-tuk-tuk-de-freetown-premier-patient-opere-et-libere-de-ses-souffrances-a-bord-du-global-mercy\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mercyships.africa\\\/fr\\\/un-conducteur-de-tuk-tuk-de-freetown-premier-patient-opere-et-libere-de-ses-souffrances-a-bord-du-global-mercy\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mercyships.africa\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/SLH250901_MOHAMED_SLH03522_BEFORE_ADMISSION_GANGWAY_RU001_HI-LO.jpg\",\"contentUrl\":\"https:\\\/\\\/mercyships.africa\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/SLH250901_MOHAMED_SLH03522_BEFORE_ADMISSION_GANGWAY_RU001_HI-LO.jpg\",\"width\":800,\"height\":533},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mercyships.africa\\\/fr\\\/un-conducteur-de-tuk-tuk-de-freetown-premier-patient-opere-et-libere-de-ses-souffrances-a-bord-du-global-mercy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mercyships.africa\\\/fr\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un conducteur de tuk-tuk de Freetown, premier patient op\u00e9r\u00e9 et lib\u00e9r\u00e9 de ses souffrances \u00e0 bord du Global Mercy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mercyships.africa\\\/#website\",\"url\":\"https:\\\/\\\/mercyships.africa\\\/\",\"name\":\"Mercy Ships Africa\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/mercyships.africa\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mercyships.africa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mercyships.africa\\\/#organization\",\"name\":\"Mercy Ships Africa\",\"url\":\"https:\\\/\\\/mercyships.africa\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mercyships.africa\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mercyships.africa\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Social-Profile-Logo-white-on-blue.jpg\",\"contentUrl\":\"https:\\\/\\\/mercyships.africa\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Social-Profile-Logo-white-on-blue.jpg\",\"width\":1000,\"height\":1000,\"caption\":\"Mercy Ships Africa\"},\"image\":{\"@id\":\"https:\\\/\\\/mercyships.africa\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mercyships.africa\",\"https:\\\/\\\/x.com\\\/mercyshipsafb\",\"https:\\\/\\\/www.instagram.com\\\/mercyships.africa\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/mercy-ships-africa\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mercyships.africa\\\/#\\\/schema\\\/person\\\/a4fe96ee15d570fe5cf8b99975f4d8b0\",\"name\":\"globalbranding\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4366c20d32788082c9349d78ce28da323844bab09fbc34a38c591503df7bf7e5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4366c20d32788082c9349d78ce28da323844bab09fbc34a38c591503df7bf7e5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4366c20d32788082c9349d78ce28da323844bab09fbc34a38c591503df7bf7e5?s=96&d=mm&r=g\",\"caption\":\"globalbranding\"},\"url\":\"https:\\\/\\\/mercyships.africa\\\/fr\\\/author\\\/globalbranding\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un conducteur de tuk-tuk de Freetown, premier patient op\u00e9r\u00e9 et lib\u00e9r\u00e9 de ses souffrances \u00e0 bord du Global Mercy - Mercy Ships Africa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mercyships.africa\/fr\/un-conducteur-de-tuk-tuk-de-freetown-premier-patient-opere-et-libere-de-ses-souffrances-a-bord-du-global-mercy\/","og_locale":"fr_FR","og_type":"article","og_title":"Un conducteur de tuk-tuk de Freetown, premier patient op\u00e9r\u00e9 et lib\u00e9r\u00e9 de ses souffrances \u00e0 bord du Global Mercy - Mercy Ships Africa","og_description":"Freetown, Sierra Leone \u2013 2 septembre 2025. Le Global Mercy\u2122, le plus grand navire-h\u00f4pital civil au monde exploit\u00e9 par l\u2019ONG Mercy Ships, a officiellement d\u00e9marr\u00e9 sa troisi\u00e8me mission cons\u00e9cutive en Sierra Leone, marqu\u00e9e par l\u2019intervention du premier patient, Mohamed, un conducteur de tuk-tuk de 40 ans. Ce moment cl\u00e9 marque le renouvellement de la mission d\u00e9di\u00e9e \u00e0 l\u2019espoir et la gu\u00e9rison tout en renfor\u00e7ant les syst\u00e8mes anesth\u00e9siques et chirurgicaux du pays.","og_url":"https:\/\/mercyships.africa\/fr\/un-conducteur-de-tuk-tuk-de-freetown-premier-patient-opere-et-libere-de-ses-souffrances-a-bord-du-global-mercy\/","og_site_name":"Mercy Ships Africa","article_publisher":"https:\/\/www.facebook.com\/mercyships.africa","article_published_time":"2025-09-05T13:37:29+00:00","article_modified_time":"2025-09-05T13:48:41+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/mercyships.africa\/wp-content\/uploads\/2025\/09\/SLH250901_MOHAMED_SLH03522_BEFORE_ADMISSION_GANGWAY_RU001_HI-LO.jpg","type":"image\/jpeg"}],"author":"globalbranding","twitter_card":"summary_large_image","twitter_creator":"@mercyshipsafb","twitter_site":"@mercyshipsafb","twitter_misc":{"\u00c9crit par":"globalbranding","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mercyships.africa\/fr\/un-conducteur-de-tuk-tuk-de-freetown-premier-patient-opere-et-libere-de-ses-souffrances-a-bord-du-global-mercy\/#article","isPartOf":{"@id":"https:\/\/mercyships.africa\/fr\/un-conducteur-de-tuk-tuk-de-freetown-premier-patient-opere-et-libere-de-ses-souffrances-a-bord-du-global-mercy\/"},"author":{"name":"globalbranding","@id":"https:\/\/mercyships.africa\/#\/schema\/person\/a4fe96ee15d570fe5cf8b99975f4d8b0"},"headline":"Un conducteur de tuk-tuk de Freetown, premier patient op\u00e9r\u00e9 et lib\u00e9r\u00e9 de ses souffrances \u00e0 bord du Global Mercy","datePublished":"2025-09-05T13:37:29+00:00","dateModified":"2025-09-05T13:48:41+00:00","mainEntityOfPage":{"@id":"https:\/\/mercyships.africa\/fr\/un-conducteur-de-tuk-tuk-de-freetown-premier-patient-opere-et-libere-de-ses-souffrances-a-bord-du-global-mercy\/"},"wordCount":1358,"commentCount":0,"publisher":{"@id":"https:\/\/mercyships.africa\/#organization"},"image":{"@id":"https:\/\/mercyships.africa\/fr\/un-conducteur-de-tuk-tuk-de-freetown-premier-patient-opere-et-libere-de-ses-souffrances-a-bord-du-global-mercy\/#primaryimage"},"thumbnailUrl":"https:\/\/mercyships.africa\/wp-content\/uploads\/2025\/09\/SLH250901_MOHAMED_SLH03522_BEFORE_ADMISSION_GANGWAY_RU001_HI-LO.jpg","keywords":["Africa","Global Mercy","Global Surgery","Mercy Ships","Sierra Leone","Surgery"],"articleSection":["Actualit\u00e9s","Communiqu\u00e9 de presse"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/mercyships.africa\/fr\/un-conducteur-de-tuk-tuk-de-freetown-premier-patient-opere-et-libere-de-ses-souffrances-a-bord-du-global-mercy\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/mercyships.africa\/fr\/un-conducteur-de-tuk-tuk-de-freetown-premier-patient-opere-et-libere-de-ses-souffrances-a-bord-du-global-mercy\/","url":"https:\/\/mercyships.africa\/fr\/un-conducteur-de-tuk-tuk-de-freetown-premier-patient-opere-et-libere-de-ses-souffrances-a-bord-du-global-mercy\/","name":"Un conducteur de tuk-tuk de Freetown, premier patient op\u00e9r\u00e9 et lib\u00e9r\u00e9 de ses souffrances \u00e0 bord du Global Mercy - Mercy Ships Africa","isPartOf":{"@id":"https:\/\/mercyships.africa\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mercyships.africa\/fr\/un-conducteur-de-tuk-tuk-de-freetown-premier-patient-opere-et-libere-de-ses-souffrances-a-bord-du-global-mercy\/#primaryimage"},"image":{"@id":"https:\/\/mercyships.africa\/fr\/un-conducteur-de-tuk-tuk-de-freetown-premier-patient-opere-et-libere-de-ses-souffrances-a-bord-du-global-mercy\/#primaryimage"},"thumbnailUrl":"https:\/\/mercyships.africa\/wp-content\/uploads\/2025\/09\/SLH250901_MOHAMED_SLH03522_BEFORE_ADMISSION_GANGWAY_RU001_HI-LO.jpg","datePublished":"2025-09-05T13:37:29+00:00","dateModified":"2025-09-05T13:48:41+00:00","breadcrumb":{"@id":"https:\/\/mercyships.africa\/fr\/un-conducteur-de-tuk-tuk-de-freetown-premier-patient-opere-et-libere-de-ses-souffrances-a-bord-du-global-mercy\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mercyships.africa\/fr\/un-conducteur-de-tuk-tuk-de-freetown-premier-patient-opere-et-libere-de-ses-souffrances-a-bord-du-global-mercy\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mercyships.africa\/fr\/un-conducteur-de-tuk-tuk-de-freetown-premier-patient-opere-et-libere-de-ses-souffrances-a-bord-du-global-mercy\/#primaryimage","url":"https:\/\/mercyships.africa\/wp-content\/uploads\/2025\/09\/SLH250901_MOHAMED_SLH03522_BEFORE_ADMISSION_GANGWAY_RU001_HI-LO.jpg","contentUrl":"https:\/\/mercyships.africa\/wp-content\/uploads\/2025\/09\/SLH250901_MOHAMED_SLH03522_BEFORE_ADMISSION_GANGWAY_RU001_HI-LO.jpg","width":800,"height":533},{"@type":"BreadcrumbList","@id":"https:\/\/mercyships.africa\/fr\/un-conducteur-de-tuk-tuk-de-freetown-premier-patient-opere-et-libere-de-ses-souffrances-a-bord-du-global-mercy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mercyships.africa\/fr\/home\/"},{"@type":"ListItem","position":2,"name":"Un conducteur de tuk-tuk de Freetown, premier patient op\u00e9r\u00e9 et lib\u00e9r\u00e9 de ses souffrances \u00e0 bord du Global Mercy"}]},{"@type":"WebSite","@id":"https:\/\/mercyships.africa\/#website","url":"https:\/\/mercyships.africa\/","name":"Mercy Ships Africa","description":"","publisher":{"@id":"https:\/\/mercyships.africa\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mercyships.africa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/mercyships.africa\/#organization","name":"Mercy Ships Africa","url":"https:\/\/mercyships.africa\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mercyships.africa\/#\/schema\/logo\/image\/","url":"https:\/\/mercyships.africa\/wp-content\/uploads\/2021\/09\/Social-Profile-Logo-white-on-blue.jpg","contentUrl":"https:\/\/mercyships.africa\/wp-content\/uploads\/2021\/09\/Social-Profile-Logo-white-on-blue.jpg","width":1000,"height":1000,"caption":"Mercy Ships Africa"},"image":{"@id":"https:\/\/mercyships.africa\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mercyships.africa","https:\/\/x.com\/mercyshipsafb","https:\/\/www.instagram.com\/mercyships.africa\/","https:\/\/www.linkedin.com\/company\/mercy-ships-africa\/"]},{"@type":"Person","@id":"https:\/\/mercyships.africa\/#\/schema\/person\/a4fe96ee15d570fe5cf8b99975f4d8b0","name":"globalbranding","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4366c20d32788082c9349d78ce28da323844bab09fbc34a38c591503df7bf7e5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4366c20d32788082c9349d78ce28da323844bab09fbc34a38c591503df7bf7e5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4366c20d32788082c9349d78ce28da323844bab09fbc34a38c591503df7bf7e5?s=96&d=mm&r=g","caption":"globalbranding"},"url":"https:\/\/mercyships.africa\/fr\/author\/globalbranding\/"}]}},"_links":{"self":[{"href":"https:\/\/mercyships.africa\/fr\/wp-json\/wp\/v2\/posts\/17813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mercyships.africa\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mercyships.africa\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mercyships.africa\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/mercyships.africa\/fr\/wp-json\/wp\/v2\/comments?post=17813"}],"version-history":[{"count":3,"href":"https:\/\/mercyships.africa\/fr\/wp-json\/wp\/v2\/posts\/17813\/revisions"}],"predecessor-version":[{"id":18995,"href":"https:\/\/mercyships.africa\/fr\/wp-json\/wp\/v2\/posts\/17813\/revisions\/18995"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mercyships.africa\/fr\/wp-json\/wp\/v2\/media\/17809"}],"wp:attachment":[{"href":"https:\/\/mercyships.africa\/fr\/wp-json\/wp\/v2\/media?parent=17813"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mercyships.africa\/fr\/wp-json\/wp\/v2\/categories?post=17813"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mercyships.africa\/fr\/wp-json\/wp\/v2\/tags?post=17813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}